{"id":219,"date":"2019-03-20T12:09:18","date_gmt":"2019-03-20T11:09:18","guid":{"rendered":"https:\/\/www.riosa.com\/?page_id=219"},"modified":"2019-05-04T21:37:12","modified_gmt":"2019-05-04T20:37:12","slug":"oleinas","status":"publish","type":"page","link":"https:\/\/www.riosa.com\/fr\/oleinas\/","title":{"rendered":"ol\u00e9ines"},"content":{"rendered":"<div id=\"cs-content\" class=\"cs-content\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Que sont les ol\u00e9ines\u00a0? Sur cette page, vous trouverez une br\u00e8ve explication de l&#039;ol\u00e9ine v\u00e9g\u00e9tale, aussi appel\u00e9e huile acide, et de sa relation avec les huiles. L&#039;ol\u00e9ine est principalement utilis\u00e9e dans l&#039;alimentation animale, mais elle est aussi couramment utilis\u00e9e dans la fabrication de savons de toilette et d&#039;autres produits de l&#039;industrie chimique. Pour un acc\u00e8s imm\u00e9diat \u00e0\u2026 <\/p>\n<div><a href=\"https:\/\/www.riosa.com\/fr\/oleinas\/\" class=\"more-link\">En savoir plus<\/a><\/div>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-layout-full-width.php","meta":{"footnotes":""},"class_list":["post-219","page","type-page","status-publish","hentry","no-post-thumbnail"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Qu\u00e9 Son las Ole\u00ednas | RIOSA - Nuestros Productos<\/title>\n<meta name=\"description\" content=\"Explicaci\u00f3n de qu\u00e9 son las ole\u00ednas vegetales. La oleina tambi\u00e9n conocida como aceite \u00e1cido, se usa en alimentaci\u00f3n animal y para hacer jab\u00f3n\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.riosa.com\/fr\/eu\/oleins\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Qu\u00e9 Son las Ole\u00ednas | RIOSA - Nuestros Productos\" \/>\n<meta property=\"og:description\" content=\"Explicaci\u00f3n de qu\u00e9 son las ole\u00ednas vegetales. La oleina tambi\u00e9n conocida como aceite \u00e1cido, se usa en alimentaci\u00f3n animal y para hacer jab\u00f3n\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.riosa.com\/fr\/eu\/oleins\/\" \/>\n<meta property=\"og:site_name\" content=\"RIOSA\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-04T20:37:12+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.riosa.com\\\/eu\\\/oleins\\\/\",\"url\":\"https:\\\/\\\/www.riosa.com\\\/eu\\\/oleins\\\/\",\"name\":\"Qu\u00e9 Son las Ole\u00ednas | RIOSA - Nuestros Productos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.riosa.com\\\/he\\\/#website\"},\"datePublished\":\"2019-03-20T11:09:18+00:00\",\"dateModified\":\"2019-05-04T20:37:12+00:00\",\"description\":\"Explicaci\u00f3n de qu\u00e9 son las ole\u00ednas vegetales. La oleina tambi\u00e9n conocida como aceite \u00e1cido, se usa en alimentaci\u00f3n animal y para hacer jab\u00f3n\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.riosa.com\\\/eu\\\/oleins\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.riosa.com\\\/eu\\\/oleins\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.riosa.com\\\/eu\\\/oleins\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.riosa.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ole\u00ednas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.riosa.com\\\/he\\\/#website\",\"url\":\"https:\\\/\\\/www.riosa.com\\\/he\\\/\",\"name\":\"RIOSA\",\"description\":\"ACEITES GRASAS Y OLE\u00cdNAS para alimentaci\u00f3n animal\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.riosa.com\\\/he\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.riosa.com\\\/he\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.riosa.com\\\/he\\\/#organization\",\"name\":\"RIOSA - Refinaci\u00f3n Industrial Oleicola S.A.\",\"url\":\"https:\\\/\\\/www.riosa.com\\\/he\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.riosa.com\\\/he\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/staging.riosa.com\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/Logo-Riosa-250.jpg\",\"contentUrl\":\"https:\\\/\\\/staging.riosa.com\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/Logo-Riosa-250.jpg\",\"width\":250,\"height\":271,\"caption\":\"RIOSA - Refinaci\u00f3n Industrial Oleicola S.A.\"},\"image\":{\"@id\":\"https:\\\/\\\/www.riosa.com\\\/he\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Que sont les ol\u00e9ines | RIOSA - Nos produits","description":"Explication de ce que sont les ol\u00e9ines v\u00e9g\u00e9tales. L&#039;ol\u00e9ine, \u00e9galement connue sous le nom d&#039;huile acide, est utilis\u00e9e dans l&#039;alimentation animale et pour fabriquer du savon.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.riosa.com\/fr\/eu\/oleins\/","og_locale":"fr_FR","og_type":"article","og_title":"Qu\u00e9 Son las Ole\u00ednas | RIOSA - Nuestros Productos","og_description":"Explicaci\u00f3n de qu\u00e9 son las ole\u00ednas vegetales. La oleina tambi\u00e9n conocida como aceite \u00e1cido, se usa en alimentaci\u00f3n animal y para hacer jab\u00f3n","og_url":"https:\/\/www.riosa.com\/fr\/eu\/oleins\/","og_site_name":"RIOSA","article_modified_time":"2019-05-04T20:37:12+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.riosa.com\/eu\/oleins\/","url":"https:\/\/www.riosa.com\/eu\/oleins\/","name":"Que sont les ol\u00e9ines | RIOSA - Nos produits","isPartOf":{"@id":"https:\/\/www.riosa.com\/he\/#website"},"datePublished":"2019-03-20T11:09:18+00:00","dateModified":"2019-05-04T20:37:12+00:00","description":"Explication de ce que sont les ol\u00e9ines v\u00e9g\u00e9tales. L&#039;ol\u00e9ine, \u00e9galement connue sous le nom d&#039;huile acide, est utilis\u00e9e dans l&#039;alimentation animale et pour fabriquer du savon.","breadcrumb":{"@id":"https:\/\/www.riosa.com\/eu\/oleins\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.riosa.com\/eu\/oleins\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.riosa.com\/eu\/oleins\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.riosa.com\/"},{"@type":"ListItem","position":2,"name":"Ole\u00ednas"}]},{"@type":"WebSite","@id":"https:\/\/www.riosa.com\/he\/#website","url":"https:\/\/www.riosa.com\/he\/","name":"RIOSA","description":"GRAISSES ET HUILES OL\u00c9INES pour l&#039;alimentation animale","publisher":{"@id":"https:\/\/www.riosa.com\/he\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.riosa.com\/he\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.riosa.com\/he\/#organization","name":"RIOSA - Raffinage Industriel Oleicola SA","url":"https:\/\/www.riosa.com\/he\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.riosa.com\/he\/#\/schema\/logo\/image\/","url":"https:\/\/staging.riosa.com\/wp-content\/uploads\/2019\/04\/Logo-Riosa-250.jpg","contentUrl":"https:\/\/staging.riosa.com\/wp-content\/uploads\/2019\/04\/Logo-Riosa-250.jpg","width":250,"height":271,"caption":"RIOSA - Refinaci\u00f3n Industrial Oleicola S.A."},"image":{"@id":"https:\/\/www.riosa.com\/he\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.riosa.com\/fr\/wp-json\/wp\/v2\/pages\/219","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.riosa.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.riosa.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.riosa.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.riosa.com\/fr\/wp-json\/wp\/v2\/comments?post=219"}],"version-history":[{"count":20,"href":"https:\/\/www.riosa.com\/fr\/wp-json\/wp\/v2\/pages\/219\/revisions"}],"predecessor-version":[{"id":592,"href":"https:\/\/www.riosa.com\/fr\/wp-json\/wp\/v2\/pages\/219\/revisions\/592"}],"wp:attachment":[{"href":"https:\/\/www.riosa.com\/fr\/wp-json\/wp\/v2\/media?parent=219"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}